{"id":3819,"date":"2023-10-10T18:36:43","date_gmt":"2023-10-10T21:36:43","guid":{"rendered":"https:\/\/www.marelli.com.br\/?post_type=tt_product&#038;p=3819"},"modified":"2024-03-14T13:04:04","modified_gmt":"2024-03-14T16:04:04","slug":"3006-like","status":"publish","type":"tt_product","link":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/3006-like\/","title":{"rendered":"3006 Like"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tt-products-lines":[11148],"tt-products-type":[11029],"tt-products-usages":[11005],"tt-products-finishing":[11154,11178,11159,11181,11191,11172,11163,11162,11161,11156,11187,11195,11189,11158,11173,11176,11177,11174,11168,11169,11150,11167,11186,11196,11152,11190,11166,11175,11157,11182,11188,11184,11194,11151,11179,11165,11183,11180,11155,11192,11171,11160,11153,11164,11185,11193,11170],"class_list":["post-3819","tt_product","type-tt_product","status-publish","format-standard","hentry","tt_line-like","tt_type-assentos","tt_usage-colab","tt_finishing-areia","tt_finishing-areia-mescla","tt_finishing-azul","tt_finishing-azul-mescla","tt_finishing-azul-marinho","tt_finishing-azul-milenial","tt_finishing-azul-noite","tt_finishing-azul-rei","tt_finishing-azul-turquesa","tt_finishing-bordo","tt_finishing-cafe","tt_finishing-cafe-iron","tt_finishing-caramelo","tt_finishing-cinza","tt_finishing-cinza-claro","tt_finishing-cinza-claro-mescla","tt_finishing-cinza-escuro-mescla","tt_finishing-cinza-escuro","tt_finishing-cinza-light","tt_finishing-coral","tt_finishing-crepe","tt_finishing-grafite","tt_finishing-grafite-vinilico","tt_finishing-grafite-iron","tt_finishing-laranja","tt_finishing-marfim","tt_finishing-marrom","tt_finishing-mescla","tt_finishing-mostarda","tt_finishing-ocre","tt_finishing-preto-vinilico","tt_finishing-preto","tt_finishing-preto-iron","tt_finishing-preto-padrao","tt_finishing-rose-mescla","tt_finishing-rose","tt_finishing-terracota","tt_finishing-verde","tt_finishing-verde-glacial","tt_finishing-verde-musgo","tt_finishing-verde-nature","tt_finishing-verde-petroleo","tt_finishing-vermelho-padrao","tt_finishing-vermelho-tijolo","tt_finishing-vinilico","tt_finishing-vinilico-metalizado","tt_finishing-violeta","ambientes-colab","ambientes-encontros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3006 Like - Marelli<\/title>\n<meta name=\"description\" content=\"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/3006-like\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3006 Like - Marelli\" \/>\n<meta property=\"og:description\" content=\"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/\" \/>\n<meta property=\"og:site_name\" content=\"Marelli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T16:04:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/\",\"name\":\"3006 Like - Marelli\",\"isPartOf\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\"},\"datePublished\":\"2023-10-10T21:36:43+00:00\",\"dateModified\":\"2024-03-14T16:04:04+00:00\",\"description\":\"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.\",\"breadcrumb\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Produtos Marelli\",\"item\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3006 Like\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/\",\"name\":\"Marelli\",\"description\":\"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3006 Like - Marelli","description":"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/3006-like\/","og_locale":"es_ES","og_type":"article","og_title":"3006 Like - Marelli","og_description":"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.","og_url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/","og_site_name":"Marelli","article_modified_time":"2024-03-14T16:04:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/","url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/","name":"3006 Like - Marelli","isPartOf":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website"},"datePublished":"2023-10-10T21:36:43+00:00","dateModified":"2024-03-14T16:04:04+00:00","description":"A 3006 Like da Marelli \u00e9 essencial para quem busca mais conforto e ergonomia no ambiente de trabalho. Acesse e confira.","breadcrumb":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/3006-like\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Produtos Marelli","item":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/"},{"@type":"ListItem","position":2,"name":"3006 Like"}]},{"@type":"WebSite","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website","url":"https:\/\/marelli.protoaws.dzigual.com.br\/","name":"Marelli","description":"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products\/3819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products"}],"about":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/types\/tt_product"}],"wp:attachment":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/media?parent=3819"}],"wp:term":[{"taxonomy":"tt_line","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-lines?post=3819"},{"taxonomy":"tt_type","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-type?post=3819"},{"taxonomy":"tt_usage","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-usages?post=3819"},{"taxonomy":"tt_finishing","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-finishing?post=3819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}