{"id":3367,"date":"2023-06-29T14:02:37","date_gmt":"2023-06-29T17:02:37","guid":{"rendered":"https:\/\/www.marelli.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/"},"modified":"2024-04-05T21:43:29","modified_gmt":"2024-04-06T00:43:29","slug":"mesa-reta-de-alto-padrao-para-escritorio-one","status":"publish","type":"tt_product","link":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/","title":{"rendered":"One Mesa Reta"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tt-products-lines":[11118],"tt-products-type":[11072],"tt-products-usages":[11112],"tt-products-finishing":[11290,11295,11291,11292,11293,11294],"class_list":["post-3367","tt_product","type-tt_product","status-publish","format-standard","hentry","tt_line-one-es","tt_type-mobiliario-es","tt_usage-direcao-es","tt_finishing-estrutura-mdp","tt_finishing-pe","tt_finishing-preto-estrutura-mdp","tt_finishing-tampo","tt_finishing-teka","tt_finishing-wengue-tampo","ambientes-colab-es","ambientes-executivo-es","ambientes-home-office-es","ambientes-operacional-es","ambientes-encontros-es-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/\" \/>\n<meta property=\"og:site_name\" content=\"Marelli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-06T00:43:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/\",\"name\":\"Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli\",\"isPartOf\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\"},\"datePublished\":\"2023-06-29T17:02:37+00:00\",\"dateModified\":\"2024-04-06T00:43:29+00:00\",\"description\":\"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.\",\"breadcrumb\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Produtos Marelli\",\"item\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Mesa Reta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/\",\"name\":\"Marelli\",\"description\":\"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli","description":"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli","og_description":"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.","og_url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/","og_site_name":"Marelli","article_modified_time":"2024-04-06T00:43:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/","url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/","name":"Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One - Marelli","isPartOf":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website"},"datePublished":"2023-06-29T17:02:37+00:00","dateModified":"2024-04-06T00:43:29+00:00","description":"Conhe\u00e7a a Mesa Reta de Alto Padr\u00e3o para Escrit\u00f3rio One da Marelli. A melhor op\u00e7\u00e3o para quem busca conforto e ergonomia. Acesse o site e solicite um or\u00e7amento.","breadcrumb":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/mesa-reta-de-alto-padrao-para-escritorio-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Produtos Marelli","item":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/"},{"@type":"ListItem","position":2,"name":"One Mesa Reta"}]},{"@type":"WebSite","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website","url":"https:\/\/marelli.protoaws.dzigual.com.br\/","name":"Marelli","description":"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products\/3367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products"}],"about":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/types\/tt_product"}],"wp:attachment":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/media?parent=3367"}],"wp:term":[{"taxonomy":"tt_line","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-lines?post=3367"},{"taxonomy":"tt_type","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-type?post=3367"},{"taxonomy":"tt_usage","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-usages?post=3367"},{"taxonomy":"tt_finishing","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-finishing?post=3367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}