{"id":3259,"date":"2023-05-05T16:00:31","date_gmt":"2023-05-05T19:00:31","guid":{"rendered":"https:\/\/www.marelli.com.br\/produtos-marelli\/2612-impact\/"},"modified":"2024-03-25T15:12:49","modified_gmt":"2024-03-25T18:12:49","slug":"2612-impact","status":"publish","type":"tt_product","link":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/2612-impact\/","title":{"rendered":"2612 IMPACT"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"tt-products-lines":[11077],"tt-products-type":[11078],"tt-products-usages":[],"tt-products-finishing":[],"class_list":["post-3259","tt_product","type-tt_product","status-publish","format-standard","hentry","tt_line-impact-es","tt_type-assentos-es","ambientes-colab-es","ambientes-lounge","ambientes-encontros-es-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2612 IMPACT - Marelli<\/title>\n<meta name=\"description\" content=\"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/2612-impact\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2612 IMPACT - Marelli\" \/>\n<meta property=\"og:description\" content=\"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/\" \/>\n<meta property=\"og:site_name\" content=\"Marelli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T18:12:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/\",\"name\":\"2612 IMPACT - Marelli\",\"isPartOf\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\"},\"datePublished\":\"2023-05-05T19:00:31+00:00\",\"dateModified\":\"2024-03-25T18:12:49+00:00\",\"description\":\"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.\",\"breadcrumb\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Produtos Marelli\",\"item\":\"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2612 IMPACT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/\",\"name\":\"Marelli\",\"description\":\"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2612 IMPACT - Marelli","description":"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/produtos-marelli\/2612-impact\/","og_locale":"es_ES","og_type":"article","og_title":"2612 IMPACT - Marelli","og_description":"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.","og_url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/","og_site_name":"Marelli","article_modified_time":"2024-03-25T18:12:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/","url":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/","name":"2612 IMPACT - Marelli","isPartOf":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website"},"datePublished":"2023-05-05T19:00:31+00:00","dateModified":"2024-03-25T18:12:49+00:00","description":"Conozca el IMPACTO 2612 de Marelli. La mejor opci\u00f3n para quienes buscan comodidad y ergonom\u00eda. Accede a la web y cotiza tu proyecto.","breadcrumb":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/longarina-cadeira-2612-impact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Produtos Marelli","item":"https:\/\/marelli.protoaws.dzigual.com.br\/produtos-marelli\/"},{"@type":"ListItem","position":2,"name":"2612 IMPACT"}]},{"@type":"WebSite","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website","url":"https:\/\/marelli.protoaws.dzigual.com.br\/","name":"Marelli","description":"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products\/3259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products"}],"about":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/types\/tt_product"}],"wp:attachment":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/media?parent=3259"}],"wp:term":[{"taxonomy":"tt_line","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-lines?post=3259"},{"taxonomy":"tt_type","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-type?post=3259"},{"taxonomy":"tt_usage","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-usages?post=3259"},{"taxonomy":"tt_finishing","embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/tt-products-finishing?post=3259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}