{"id":2774,"date":"2023-02-08T14:36:02","date_gmt":"2023-02-08T17:36:02","guid":{"rendered":"https:\/\/www.marelli.com.br\/?post_type=cases&#038;p=2774"},"modified":"2023-08-10T18:12:35","modified_gmt":"2023-08-10T21:12:35","slug":"lufthansa","status":"publish","type":"cases","link":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/cases\/lufthansa\/","title":{"rendered":"Lufthansa"},"content":{"rendered":"<p>Lufthansa inaugur\u00f3 una nueva sede de aerol\u00ednea en Brasil. El reto era pensar en una oficina polivalente, con una divisi\u00f3n entre espacios cerrados y abiertos y que, principalmente, solucionara el tema del aprovechamiento del espacio. Para ello eligi\u00f3 a Marelli como proveedor de mobiliario.Para el \u00e9xito del proyecto, el equipo de AFGR Arquitettos pens\u00f3 en cinco pilares: sectorizaci\u00f3n, uso de espacios abiertos, espacios flexibles, uso de vol\u00famenes y uso de materiales con lenguaje industrial.<\/p>\n<p>Sectorizar los espacios fue fundamental, ya que ayud\u00f3 a definir d\u00f3nde utilizar\u00edan el concepto de espacio abierto y d\u00f3nde estar\u00edan los espacios m\u00e1s cerrados. El proyecto unific\u00f3 toda la losa, dividiendo la oficina en recepci\u00f3n y hall de ascensores. Adem\u00e1s, en el margen izquierdo del plan se definieron las \u00e1reas financiera, administrativa y de recursos humanos. En este caso no trabajamos con el concepto abierto, ya que no era el perfil de los empleados. Se reserv\u00f3 un espacio abierto para el equipo de Marketing, repartido entre las habitaciones de los dos directivos.<\/p>\n<p>Finalmente, aprovechamos toda la volumetr\u00eda del entorno, creando el concepto desde un lenguaje industrial, con instalaciones a la vista, zonas sin revestimiento, uso de chapas, hormig\u00f3n y materias primas.<\/p>\n","protected":false},"featured_media":1016,"template":"","meta":{"_acf_changed":false},"class_list":["post-2774","cases","type-cases","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lufthansa - Marelli<\/title>\n<meta name=\"description\" content=\"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marelli.protoaws.dzigual.com.br\/es\/cases\/lufthansa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lufthansa - Marelli\" \/>\n<meta property=\"og:description\" content=\"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/\" \/>\n<meta property=\"og:site_name\" content=\"Marelli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-10T21:12:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/\",\"name\":\"Lufthansa - Marelli\",\"isPartOf\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg\",\"datePublished\":\"2023-02-08T17:36:02+00:00\",\"dateModified\":\"2023-08-10T21:12:35+00:00\",\"description\":\"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.\",\"breadcrumb\":{\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg\",\"contentUrl\":\"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg\",\"width\":2560,\"height\":1704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cases\",\"item\":\"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lufthansa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/marelli.protoaws.dzigual.com.br\/#website\",\"url\":\"https:\/\/marelli.protoaws.dzigual.com.br\/\",\"name\":\"Marelli\",\"description\":\"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lufthansa - Marelli","description":"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/cases\/lufthansa\/","og_locale":"es_ES","og_type":"article","og_title":"Lufthansa - Marelli","og_description":"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.","og_url":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/","og_site_name":"Marelli","article_modified_time":"2023-08-10T21:12:35+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/","url":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/","name":"Lufthansa - Marelli","isPartOf":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage"},"image":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage"},"thumbnailUrl":"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg","datePublished":"2023-02-08T17:36:02+00:00","dateModified":"2023-08-10T21:12:35+00:00","description":"Accede y conoce m\u00e1s sobre el caso Lufthansa de Marelli.","breadcrumb":{"@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#primaryimage","url":"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg","contentUrl":"https:\/\/marelli.protoaws.dzigual.com.br\/wp-content\/uploads\/2021\/03\/02_Staff-IMG_0610-1-scaled.jpg","width":2560,"height":1704},{"@type":"BreadcrumbList","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/lufthansa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cases","item":"https:\/\/marelli.protoaws.dzigual.com.br\/cases\/"},{"@type":"ListItem","position":2,"name":"Lufthansa"}]},{"@type":"WebSite","@id":"https:\/\/marelli.protoaws.dzigual.com.br\/#website","url":"https:\/\/marelli.protoaws.dzigual.com.br\/","name":"Marelli","description":"H\u00e1 mais de 37 anos desenvolvendo solu\u00e7\u00f5es inovadoras de mobili\u00e1rio corporativo com design e ergonomia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marelli.protoaws.dzigual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/cases\/2774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/cases"}],"about":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/types\/cases"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/media\/1016"}],"wp:attachment":[{"href":"https:\/\/marelli.protoaws.dzigual.com.br\/es\/wp-json\/wp\/v2\/media?parent=2774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}